{"id":968,"date":"2017-09-20T18:25:20","date_gmt":"2017-09-20T18:25:20","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=968"},"modified":"2017-09-26T16:29:33","modified_gmt":"2017-09-26T16:29:33","slug":"como-ajudar-na-preservacao-da-camada-de-ozonio","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2017\/09\/20\/como-ajudar-na-preservacao-da-camada-de-ozonio\/","title":{"rendered":"Como ajudar na preserva\u00e7\u00e3o da Camada de Oz\u00f4nio"},"content":{"rendered":"<p>Pode parecer um assunto ultrapassado, mas a verdade \u00e9 que a camada de oz\u00f4nio ainda precisa ser preservada. Tanto \u00e9 que a ONU (Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas) instituiu o dia 16 de setembro para chamar aten\u00e7\u00e3o para esse problema ambiental. Ter consci\u00eancia j\u00e1 \u00e9 o primeiro passo. Depois disso, \u00e9 importante passar a ter atitudes simples no dia a dia para mudar esse quadro. O Zero Perrengue explica a import\u00e2ncia de reverter essa situa\u00e7\u00e3o e quais medidas voc\u00ea pode adotar.<\/p>\n<h2><strong>Mas afinal, o que \u00e9 a camada de oz\u00f4nio<\/strong><\/h2>\n<p>A camada de oz\u00f4nio \u00e9 um tipo de capa composta por g\u00e1s oz\u00f4nio (O3) que filtra cerca de 95% dos raios ultravioletas B (UVB) emitidos pelo sol.\u00a0 Sem ela, a fotoss\u00edntese realizada pelas plantas ficaria prejudicada e aumentariam os casos de doen\u00e7as ligadas \u00e0 exposi\u00e7\u00e3o solar, como c\u00e2ncer de pele e alguns tipos de alergias. Sem contar que afetaria toda a din\u00e2mica ambiental do planeta.<\/p>\n<h2><strong>O que fazer para ajudar?<\/strong><\/h2>\n<h3><strong>D\u00ea um descanso para o seu carro<\/strong><\/h3>\n<p>Pode parecer uma dica velha, mas trocar o seu carro \u2013 pelo menos algumas vezes na semana \u2013 por uma bicicleta ajuda na preserva\u00e7\u00e3o da camada de oz\u00f4nio. Os autom\u00f3veis movidos \u00e0 combust\u00edvel f\u00f3ssil (s\u00e3o combust\u00edveis formados por meio de processos naturais, como a decomposi\u00e7\u00e3o de organismos mortos soterrados .) emitem g\u00e1s carb\u00f4nico que tamb\u00e9m causam danos \u00e0 capa protetora do planeta.<\/p>\n<h3><strong>Fique atento ao comprar um eletrodom\u00e9stico<\/strong><\/h3>\n<p>Antes de comprar um eletrodom\u00e9stico fique de olho para saber se ele \u00e9 livre de um g\u00e1s chamado Clorofluorcarboneto (CFC). Essa subst\u00e2ncia \u00e9 um composto baseado em carbono que cont\u00e9m cloro e fl\u00faor e \u00e9 respons\u00e1vel pela redu\u00e7\u00e3o da camada de oz\u00f4nio. Esse g\u00e1s era muito utilizado como aeross\u00f3is (que hoje j\u00e1 s\u00e3o proibidos no Brasil) e gases para refrigera\u00e7\u00e3o. Ent\u00e3o, na hora de escolher uma geladeira, verifique se o modelo escolhido possui o selo tipo Green.<\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-971\" src=\"http:\/\/api.blog.brasilcap.com.br\/wp-content\/uploads\/2017\/09\/SELO-FSC.jpg\" alt=\"SELO-FSC\" width=\"150\" height=\"150\" \/><\/p>\n<h3><strong>Verifique seu ar condicionado<\/strong><\/h3>\n<p>O Brasil \u00e9 um pa\u00eds tropical e na maior parte do ano as temperaturas s\u00e3o elevadas. Consequentemente, o uso do ar condicionado \u00e9 quase inevit\u00e1vel. E n\u00e3o h\u00e1 problema algum nisso, basta voc\u00ea fazer com frequ\u00eancia uma limpeza e verificar se est\u00e1 tudo funcionando corretamente. Se este aparelho n\u00e3o estiver funcionando adequadamente ou vazando g\u00e1s, ser\u00e1 emitido CFC na atmosfera.<\/p>\n<p>&nbsp;<\/p>\n<p><em>Preservar a camada de oz\u00f4nio e a natureza de forma geral faz parte de um dos 17 Objetivos Globais de Desenvolvimento Sustent\u00e1vel da ONU. <\/em><a href=\"https:\/\/nacoesunidas.org\/pos2015\/ods13\/\"><em>A ODS13 diz respeito \u00e0s a\u00e7\u00f5es contra a mudan\u00e7a global do clima<\/em><\/a><em>, o objetivo \u00e9 tomar medidas urgentes para combater a mudan\u00e7a clim\u00e1tica e seus impactos.<\/em><\/p>\n<p><img loading=\"lazy\" decoding=\"async\" class=\"aligncenter size-full wp-image-972\" src=\"http:\/\/api.blog.brasilcap.com.br\/wp-content\/uploads\/2017\/09\/13.png\" alt=\"13\" width=\"161\" height=\"161\" srcset=\"https:\/\/blog-homolog.brasilcap.com.br\/wp-content\/uploads\/2017\/09\/13.png 161w, https:\/\/blog-homolog.brasilcap.com.br\/wp-content\/uploads\/2017\/09\/13-150x150.png 150w\" sizes=\"auto, (max-width: 161px) 100vw, 161px\" \/><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Pode parecer um assunto ultrapassado, mas a verdade \u00e9 que a camada de oz\u00f4nio ainda precisa ser preservada. Tanto \u00e9 que a ONU (Organiza\u00e7\u00e3o das Na\u00e7\u00f5es Unidas) instituiu o dia 16 de setembro para chamar aten\u00e7\u00e3o para esse problema ambiental. Ter consci\u00eancia j\u00e1 \u00e9 o primeiro passo. Depois disso, \u00e9 importante passar a ter atitudes [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":970,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[286,21,282,19],"class_list":["post-968","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meio_ambiente","category-recente","tag-dia-mundial-para-a-preservacao-da-camada-do-ozonio","tag-meio-ambiente","tag-ods","tag-sustentabilidade"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/968","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=968"}],"version-history":[{"count":1,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/968\/revisions"}],"predecessor-version":[{"id":973,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/968\/revisions\/973"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/970"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=968"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=968"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=968"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}