{"id":823,"date":"2017-07-24T20:18:58","date_gmt":"2017-07-24T20:18:58","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=823"},"modified":"2017-09-05T20:18:49","modified_gmt":"2017-09-05T20:18:49","slug":"descubra-como-reformar-a-casa-sem-dor-de-cabeca","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2017\/07\/24\/descubra-como-reformar-a-casa-sem-dor-de-cabeca\/","title":{"rendered":"Descubra como reformar a casa sem dor de cabe\u00e7a"},"content":{"rendered":"<p>Planejamento financeiro \u00e9 o segredo para realizar planos sem passar perrengue. Antes de come\u00e7ar uma reforma, \u00e9 preciso se perguntar: de quanto eu preciso? De onde eu posso cortar custos e por quanto tempo? Confira as nossas dicas e m\u00e3os \u00e0 obra:<\/p>\n<p>&#8211; Acabe com as d\u00edvidas<\/p>\n<p>Tem muitas d\u00edvidas \u00e0 pagar? Antes de come\u00e7ar uma reforma \u00e9 importante quitar seus d\u00e9bitos.<\/p>\n<p>&#8211; Estabele\u00e7a prioridades<\/p>\n<p>Voc\u00ea precisa de quanto para manter a casa mensalmente? Evite comprometer mais de 15% da sua renda familiar com a reforma.<\/p>\n<p>&#8211; Procure um profissional qualificado<\/p>\n<p>Contratar um profissional qualificado para comandar a obra pode evitar desperd\u00edcios e gastos desnecess\u00e1rios por falta de conhecimento e planejamento.<\/p>\n<p>&#8211; N\u00e3o se afobe<\/p>\n<p>A reforma ser\u00e1 maior do que voc\u00ea esperava? Divida-a em etapas para serem cumpridas conforme o seu or\u00e7amento permitir.<\/p>\n<p>&#8211; Programe-se<\/p>\n<p>Compras antecipadas possibilitam maior negocia\u00e7\u00e3o com fornecedores e costumam render bons descontos.<\/p>\n<p>&#8211; Aproveite promo\u00e7\u00f5es<\/p>\n<p>Entre o final de dezembro e o come\u00e7o de janeiro, muitas lojas promovem sald\u00f5es de desconto. Esteja atento e n\u00e3o perca a oportunidade de pagar mais barato por bons produtos.<\/p>\n<p>Com organiza\u00e7\u00e3o, fica mais f\u00e1cil realizar seus planos. E se existe um produto que ajuda voc\u00ea a se organizar e realizar seus planos \u00e9 o Ourocap. Com esse t\u00edtulo de capitaliza\u00e7\u00e3o comercializado pelo Banco do Brasil, voc\u00ea guarda dinheiro e, ao mesmo tempo, concorre a sorteios com pr\u00eamios de at\u00e9 R$ 10 milh\u00f5es. Ao final da vig\u00eancia, mesmo n\u00e3o sendo sorteado, voc\u00ea recebe de volta 100% do valor pago no t\u00edtulo j\u00e1 corrigido. D\u00e1 para come\u00e7ar<\/p>\n<p>pagando um pouquinho por m\u00eas, somente R$ 30,00.<\/p>\n<p>Se interessou? Ent\u00e3o acesse <a href=\"http:\/\/www.brasilcap.com.br\/ourocap\">www.brasilcap.com.br\/ourocap<\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Planejamento financeiro \u00e9 o segredo para realizar planos sem passar perrengue. Antes de come\u00e7ar uma reforma, \u00e9 preciso se perguntar: de quanto eu preciso? De onde eu posso cortar custos e por quanto tempo? Confira as nossas dicas e m\u00e3os \u00e0 obra: &#8211; Acabe com as d\u00edvidas Tem muitas d\u00edvidas \u00e0 pagar? Antes de come\u00e7ar [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":824,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10],"tags":[40,123,43,244,45,23,48,25,47,242,243,72],"class_list":["post-823","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financas","category-recente","tag-calcular","tag-casa","tag-categorizar-gastos","tag-construcao","tag-defina-prioridades","tag-dia-a-dia","tag-disciplina-financeira","tag-economia","tag-financas","tag-obras","tag-reforma","tag-vida"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/823","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=823"}],"version-history":[{"count":1,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/823\/revisions"}],"predecessor-version":[{"id":825,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/823\/revisions\/825"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/824"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=823"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=823"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=823"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}