{"id":820,"date":"2017-07-24T20:08:20","date_gmt":"2017-07-24T20:08:20","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=820"},"modified":"2017-09-05T20:18:57","modified_gmt":"2017-09-05T20:18:57","slug":"5-produtos-de-limpeza-ecologicos-para-fazer-em-casa","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2017\/07\/24\/5-produtos-de-limpeza-ecologicos-para-fazer-em-casa\/","title":{"rendered":"5 produtos de limpeza ecol\u00f3gicos para fazer em casa"},"content":{"rendered":"<p>Produtos de limpeza possuem centenas de subst\u00e2ncias qu\u00edmicas com efeitos t\u00f3xicos. Uma delas \u00e9 o &#8220;fosfato&#8221;, que, em contato com o meio ambiente, diminui o n\u00edvel de oxig\u00eanio da \u00e1gua e pode causar a morte de animais e plantas. Para reduzir impactos e contribuir com o meio ambiente, confira as receitas que selecionamos:<\/p>\n<p>1 &#8211; Sab\u00e3o l\u00edquido para lavar lou\u00e7a:<\/p>\n<p>2 litros de \u00e1gua;<br \/>\n1 sab\u00e3o caseiro ralado;<br \/>\n1 colher de \u00f3leo de r\u00edcino;<br \/>\n1 colher de a\u00e7\u00facar.<\/p>\n<p>Ferva todos os ingredientes at\u00e9 dissolver e engarrafe.<\/p>\n<p>2 &#8211; Desinfetante para banheiro<\/p>\n<p>1 litro de \u00e1lcool (de prefer\u00eancia 70\u00ba);<br \/>\n4 litros de \u00e1gua;<br \/>\n1 sab\u00e3o caseiro;<br \/>\nFolhas de eucalipto.<\/p>\n<p>Deixe as folhas de eucalipto de molho no \u00e1lcool por 2 dias. Ferva a \u00e1gua com o sab\u00e3o ralado at\u00e9 dissolver. Junte a ess\u00eancia de eucalipto e a \u00e1gua e engarrafe.<\/p>\n<p>3 \u2013 Limpador de vidros<\/p>\n<p>3 colheres de vinagre;<br \/>\n11 litros de \u00e1gua.<\/p>\n<p>Use as colheres de vinagre dilu\u00eddas na \u00e1gua quente. Para secar, utilize tecido de algod\u00e3o reutilizado ou jornais velhos.<\/p>\n<p>4 \u2013 Amaciantes de roupas<\/p>\n<p>\u00bd copo de vinagre<br \/>\nOU<br \/>\n\u00bc de copo de bicarbonato<\/p>\n<p>Adicione o copo de vinagre ou o de copo de bicarbonato durante o enx\u00e1gue.<\/p>\n<p>5 \u2013 Desodorante de ambientes<\/p>\n<p>O desodorante de ambientes pode ser substitu\u00eddo por uma solu\u00e7\u00e3o de ervas com vinagre ou suco de lim\u00e3o. Al\u00e9m de gastar menos dinheiro, voc\u00ea evita doen\u00e7as respirat\u00f3rias e alergias.<\/p>\n<p>Curtiu as dicas? Compartilhe com os seus amigos!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Produtos de limpeza possuem centenas de subst\u00e2ncias qu\u00edmicas com efeitos t\u00f3xicos. Uma delas \u00e9 o &#8220;fosfato&#8221;, que, em contato com o meio ambiente, diminui o n\u00edvel de oxig\u00eanio da \u00e1gua e pode causar a morte de animais e plantas. Para reduzir impactos e contribuir com o meio ambiente, confira as receitas que selecionamos: 1 &#8211; [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":821,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[5,10],"tags":[26,238,236,240,23,241,235,234,237,239,18,22],"class_list":["post-820","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-meio_ambiente","category-recente","tag-agua","tag-banheiro","tag-cozinha","tag-cuidados-com-o-lar","tag-dia-a-dia","tag-ingredientes","tag-limpeza","tag-material-de-limpeza","tag-quarto","tag-solucao","tag-sustentabilidade-em-casa","tag-sustentavel"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/820","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=820"}],"version-history":[{"count":1,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/820\/revisions"}],"predecessor-version":[{"id":822,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/820\/revisions\/822"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/821"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=820"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=820"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=820"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}