{"id":802,"date":"2017-07-10T19:30:33","date_gmt":"2017-07-10T19:30:33","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=802"},"modified":"2017-07-10T19:30:33","modified_gmt":"2017-07-10T19:30:33","slug":"5-dicas-para-economizar-agua-em-casa","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2017\/07\/10\/5-dicas-para-economizar-agua-em-casa\/","title":{"rendered":"5 dicas para economizar \u00e1gua em casa"},"content":{"rendered":"<p>Segundo o World Resources Institute, ligado \u00e0 ONU, mais de 1 bilh\u00e3o de pessoas vive em \u00e1reas com escassez de \u00e1gua. E acredite: at\u00e9 2025, esse n\u00famero pode dobrar! Para colaborar com o meio ambiente e reduzir gastos, selecionamos 5 dicas simples. Confira:<\/p>\n<p><strong>1 &#8211; Use a m\u00e1quina de lavar menos vezes na semana<\/strong><\/p>\n<p>Nada de usar a m\u00e1quina de lavar muitas vezes. O ideal \u00e9 acumular uma grande quantidade de roupas e escolher um dia para bat\u00ea-las. \u00a0Al\u00e9m disso, a \u00e1gua que a m\u00e1quina de lavar utiliza para o enx\u00e1gue pode ser reutilizada para limpar o piso da cozinha, quintal e o da pr\u00f3pria lavanderia. Basta retirar a mangueira de vaz\u00e3o do cano e desviar o fluxo para um balde. O mais interessante \u00e9 que, dependendo do n\u00famero de enx\u00e1gues, \u00e9 poss\u00edvel economizar at\u00e9 3 baldes cheios por lavagem e reutilizar a \u00e1gua em outras tarefas di\u00e1rias.<\/p>\n<h3><strong>2 &#8211; Aproveite o inverno e use um balde para captar a \u00e1gua do chuveiro<\/strong><\/h3>\n<p>Essa dica \u00e9 para quem desperdi\u00e7a alguns minutos esperando a \u00e1gua do chuveiro esquentar. Voc\u00ea pode colocar um balde embaixo da ducha enquanto o chuveiro n\u00e3o esquenta e, posteriormente, usar a \u00e1gua para dar descarga no vaso sanit\u00e1rio, por exemplo. A economia pode chegar a 10 litros, nesses casos.<\/p>\n<p><strong>3 &#8211; Trate a \u00e1gua da piscina<\/strong><\/p>\n<p>Ao inv\u00e9s de trocar a \u00e1gua da piscina v\u00e1rias vezes ao m\u00eas, sempre que a piscina n\u00e3o estiver sendo utilizada, a dica \u00e9 deix\u00e1-la coberta. Assim, a perda por evapora\u00e7\u00e3o diminui em at\u00e9 90%. Em uma piscina de tamanho m\u00e9dio, isso representa economia mensal de 3.785 litros de \u00e1gua \u2013 quantidade suficiente para suprir as necessidades de uma fam\u00edlia de quatro pessoas por cerca de um ano e meio.<\/p>\n<h3>4 &#8211; Invista em acess\u00f3rios<\/h3>\n<p>Na loja de utilidades dom\u00e9sticas ou ferragens, pergunte sobre os arejadores ou pelos redutores de vaz\u00e3o, itens que podem reduzir o consumo em pelo menos 20%. Outra op\u00e7\u00e3o s\u00e3o as v\u00e1lvulas de descarga de duplo acionamento, que permite a economia de tr\u00eas ou seis litros d\u2019\u00e1gua.<\/p>\n<p><strong>5 \u2013 Boca aberta, torneira fechada<\/strong><br \/>\nN\u00e3o deixe a \u00e1gua correndo enquanto estiver escovando os dentes. Uma pessoa pode economizar 1,9 milh\u00e3o de litros de \u00e1gua ao longo da vida simplesmente escovando os dentes com a torneira fechada. Se duas pessoas fizerem isso, a quantidade de \u00e1gua economizada equivale a uma piscina ol\u00edmpica e meia. Quer mais? Se todos os moradores do Brasil adotarem o h\u00e1bito, a \u00e1gua economizada durante um m\u00eas equivaler\u00e1 ao volume de um dia e meio de \u00e1gua correndo pelas Cataratas do Igua\u00e7u.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo o World Resources Institute, ligado \u00e0 ONU, mais de 1 bilh\u00e3o de pessoas vive em \u00e1reas com escassez de \u00e1gua. E acredite: at\u00e9 2025, esse n\u00famero pode dobrar! Para colaborar com o meio ambiente e reduzir gastos, selecionamos 5 dicas simples. Confira: 1 &#8211; Use a m\u00e1quina de lavar menos vezes na semana Nada [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":803,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,5],"tags":[26,24,69,23,27,21,17,19,18,22,72],"class_list":["post-802","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-meio_ambiente","tag-agua","tag-cotidiano","tag-cuidados","tag-dia-a-dia","tag-economizar-agua","tag-meio-ambiente","tag-reciclagem","tag-sustentabilidade","tag-sustentabilidade-em-casa","tag-sustentavel","tag-vida"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/802","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=802"}],"version-history":[{"count":1,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/802\/revisions"}],"predecessor-version":[{"id":804,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/802\/revisions\/804"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/803"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=802"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=802"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=802"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}