{"id":713,"date":"2017-05-19T14:26:19","date_gmt":"2017-05-19T14:26:19","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=713"},"modified":"2017-08-29T17:37:34","modified_gmt":"2017-08-29T17:37:34","slug":"4-dicas-para-economizar-na-hora-de-comprar-um-computador","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2017\/05\/19\/4-dicas-para-economizar-na-hora-de-comprar-um-computador\/","title":{"rendered":"4 dicas para economizar na hora de comprar um computador"},"content":{"rendered":"<p>O primeiro e principal erro de quem deseja adquirir um computador novo \u00e9 o impulso. \u00c9 preciso pesquisar pre\u00e7os e marcas antes de tomar qualquer decis\u00e3o. Mas n\u00e3o para por a\u00ed! Confira outras dicas:<\/p>\n<p>1 &#8211; Armazenamento interno:<\/p>\n<p>Ser\u00e1 que voc\u00ea precisa mesmo de todo o espa\u00e7o que um computador caro disponibiliza? Para a maioria dos usu\u00e1rios b\u00e1sicos, 256 GB s\u00e3o suficiente para guardar arquivos, programas, fotos e v\u00eddeos.<\/p>\n<p>2 &#8211; Tamanho e qualidade da tela<\/p>\n<p>Um notebook com tela mais compacta, em HD, pode valer mais a pena do que um equipamento caro e com design maior &#8211; al\u00e9m de ser mais f\u00e1cil de transportar no dia a dia.<\/p>\n<p>3 &#8211; Leitor de Blu-Ray<\/p>\n<p>Alguns computadores v\u00eam com leitores Blu-Ray, o que aumenta o pre\u00e7o das m\u00e1quinas. Se voc\u00ea j\u00e1 tem um em casa, eles tornam-se dispens\u00e1veis.<\/p>\n<p>4 &#8211; Reaproveite acess\u00f3rios e perif\u00e9ricos<\/p>\n<p>Reaproveitar acess\u00f3rios e perif\u00e9ricos do seu computador antigo &#8211; mouse, teclado, caixas de som, microfones e fones de ouvido &#8211; \u00e9 uma \u00f3tima op\u00e7\u00e3o para gastar menos. N\u00e3o hesite!<\/p>\n<p>Gostou das dicas? Siga passo a passo e sentir\u00e1 a diferen\u00e7a no bolso!<\/p>\n","protected":false},"excerpt":{"rendered":"<p>O primeiro e principal erro de quem deseja adquirir um computador novo \u00e9 o impulso. \u00c9 preciso pesquisar pre\u00e7os e marcas antes de tomar qualquer decis\u00e3o. Mas n\u00e3o para por a\u00ed! Confira outras dicas: 1 &#8211; Armazenamento interno: Ser\u00e1 que voc\u00ea precisa mesmo de todo o espa\u00e7o que um computador caro disponibiliza? Para a maioria [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":714,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[2,10],"tags":[188,59,25,183,189],"class_list":["post-713","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-financas","category-recente","tag-computador","tag-dicas","tag-economia","tag-educacao-financeira","tag-tecnologia"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/713","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=713"}],"version-history":[{"count":1,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/713\/revisions"}],"predecessor-version":[{"id":715,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/713\/revisions\/715"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/714"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=713"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=713"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=713"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}