{"id":540,"date":"2017-02-20T17:25:02","date_gmt":"2017-02-20T17:25:02","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=540"},"modified":"2017-02-20T17:25:02","modified_gmt":"2017-02-20T17:25:02","slug":"3-dicas-simples-para-manter-a-cidade-limpa-durante-a-folia","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2017\/02\/20\/3-dicas-simples-para-manter-a-cidade-limpa-durante-a-folia\/","title":{"rendered":"3 dicas simples para manter a cidade limpa durante a folia"},"content":{"rendered":"<p>Segundo dados das empresas de limpeza, a quantidade de lixo recolhida ap\u00f3s a folia cresce cerca de 40% a cada ano, o que aumenta o risco de enchentes e prolifera\u00e7\u00e3o de mosquitos transmissores de doen\u00e7as. Confira as dicas que selecionamos e curta a folia de forma consciente:<\/p>\n<p>1 &#8211; N\u00e3o jogue lixo no ch\u00e3o:<\/p>\n<p>Procure a lixeira mais pr\u00f3xima. N\u00e3o achou? Guarde o seu lixo at\u00e9 encontr\u00e1-la. Uma outra alternativa \u00e9 levar a sua pr\u00f3pria sacolinha.<\/p>\n<p>2 \u2013 Use copos reutiliz\u00e1veis:<\/p>\n<p>Nada de acumular copos descart\u00e1veis! Aposte nos reutiliz\u00e1veis e evite o desperd\u00edcio.<\/p>\n<p>3 \u2013 N\u00e3o fa\u00e7a xixi na rua:<\/p>\n<p>Bateu vontade de fazer xixi? Utilize os banheiros qu\u00edmicos disponibilizados pela Prefeitura da sua cidade.<\/p>\n<p>Fa\u00e7a a sua parte e colabore para uma cidade mais limpa.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Segundo dados das empresas de limpeza, a quantidade de lixo recolhida ap\u00f3s a folia cresce cerca de 40% a cada ano, o que aumenta o risco de enchentes e prolifera\u00e7\u00e3o de mosquitos transmissores de doen\u00e7as. Confira as dicas que selecionamos e curta a folia de forma consciente: 1 &#8211; N\u00e3o jogue lixo no ch\u00e3o: Procure [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":541,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,5],"tags":[105,29,114,116,21,11,17,115,32,19,18,22,72],"class_list":["post-540","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-meio_ambiente","tag-carnaval","tag-embalagens-biodegradaveis","tag-lixo","tag-lixo-na-rua","tag-meio-ambiente","tag-produtos-biodegradaveis","tag-reciclagem","tag-rua","tag-sacolas-plasticas","tag-sustentabilidade","tag-sustentabilidade-em-casa","tag-sustentavel","tag-vida"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/540","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=540"}],"version-history":[{"count":1,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/540\/revisions"}],"predecessor-version":[{"id":542,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/540\/revisions\/542"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/541"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=540"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=540"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=540"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}