{"id":3403,"date":"2023-09-06T18:55:41","date_gmt":"2023-09-06T18:55:41","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=3403"},"modified":"2023-09-06T18:55:41","modified_gmt":"2023-09-06T18:55:41","slug":"financas-verdes","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2023\/09\/06\/financas-verdes\/","title":{"rendered":"Finan\u00e7as Verdes"},"content":{"rendered":"<p><span data-contrast=\"auto\">Voc\u00ea sabe o que s\u00e3o Finan\u00e7as Verdes? <\/span><span data-contrast=\"auto\">\ud83c\udf33\ud83c\udf43<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A busca por solu\u00e7\u00f5es para os desafios ambientais e clim\u00e1ticos do nosso tempo tem levado a uma crescente conscientiza\u00e7\u00e3o sobre a import\u00e2ncia das \u201cFinan\u00e7as Verdes\u201d. Esse termo, muito falado nos \u00faltimos anos, refere-se a um mercado financeiro sustent\u00e1vel, que busca n\u00e3o apenas o lucro, mas tamb\u00e9m o bem-estar do planeta e das gera\u00e7\u00f5es futuras. Tratam-se de iniciativas\u00a0no setor financeiro e\u00a0de capitais destinadas a atribuir valor de mercado, com objetivo tamb\u00e9m\u00a0de financiar projetos ambientalmente sustent\u00e1veis.\u00a0<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">As Finan\u00e7as Verdes contribuem para uma economia consciente e de baixo carbono. \u00c9 um modelo econ\u00f4mico que garante o futuro do planeta.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Segundo o levantamento da Consultoria e Avalia\u00e7\u00e3o ESG \u2013 NINT, no Brasil, as emiss\u00f5es de cr\u00e9dito sustent\u00e1veis via mercado de capitais v\u00eam crescendo anualmente desde 2015. Os t\u00edtulos verdes corresponderam a 70% das 287 opera\u00e7\u00f5es e 57% do volume de emiss\u00f5es entre 2015 e 2022, movimentando R$ 199,28 bilh\u00f5es.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O mercado financeiro sustent\u00e1vel \u00e9 baseado em princ\u00edpios que visam \u00e0 integra\u00e7\u00e3o de crit\u00e9rios ambientais, sociais e de governan\u00e7a (ESG) nas decis\u00f5es de investimento. Isso significa que, ao escolher onde aportar seu dinheiro, os investidores consideram n\u00e3o apenas o potencial retorno financeiro, mas tamb\u00e9m o impacto que essa decis\u00e3o ter\u00e1 no meio ambiente e na sociedade.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Uma das principais caracter\u00edsticas do mercado financeiro sustent\u00e1vel, como j\u00e1 mencionado, \u00e9 o direcionamento em projetos e empresas que estejam alinhados com os objetivos de sustentabilidade. Isso inclui, por exemplo, investimentos em energias renov\u00e1veis, efici\u00eancia energ\u00e9tica, agricultura sustent\u00e1vel, transporte limpo e tecnologias verdes. Esses investimentos n\u00e3o apenas ajudam a combater as mudan\u00e7as clim\u00e1ticas, mas tamb\u00e9m criam oportunidades de neg\u00f3cios e empregos em setores que s\u00e3o essenciais para o futuro sustent\u00e1vel do planeta.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">Al\u00e9m disso, as Finan\u00e7as Verdes incentivam a transpar\u00eancia e a responsabilidade das empresas em rela\u00e7\u00e3o \u00e0s suas pr\u00e1ticas ambientais e sociais. Isso significa que as companhias que desejam atrair investidores conscientes precisam demonstrar seu compromisso com a sustentabilidade, fornecendo informa\u00e7\u00f5es detalhadas sobre suas atividades e impactos.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">O mercado financeiro sustent\u00e1vel tamb\u00e9m est\u00e1 impulsionando a inova\u00e7\u00e3o e o desenvolvimento de novos produtos financeiros. Por exemplo, os t\u00edtulos verdes s\u00e3o uma forma de capta\u00e7\u00e3o de recursos que direciona o dinheiro dos investidores para projetos espec\u00edficos de baixo impacto ambiental. Al\u00e9m disso, os fundos de investimento ESG permitem que os investidores diversifiquem suas carteiras enquanto mant\u00eam um foco na sustentabilidade.<\/span><span data-ccp-props=\"{&quot;201341983&quot;:0,&quot;335551550&quot;:6,&quot;335551620&quot;:6,&quot;335559739&quot;:160,&quot;335559740&quot;:259}\">\u00a0<\/span><\/p>\n<p><span data-contrast=\"auto\">A Brasilcap acredita na sustentabilidade e na import\u00e2ncia do consumo e economia conscientes. Bora, conhecer mais sobre o assunto? Fique conectado aqui.\u00a0<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea sabe o que s\u00e3o Finan\u00e7as Verdes? \ud83c\udf33\ud83c\udf43\u00a0 A busca por solu\u00e7\u00f5es para os desafios ambientais e clim\u00e1ticos do nosso tempo tem levado a uma crescente conscientiza\u00e7\u00e3o sobre a import\u00e2ncia das \u201cFinan\u00e7as Verdes\u201d. Esse termo, muito falado nos \u00faltimos anos, refere-se a um mercado financeiro sustent\u00e1vel, que busca n\u00e3o apenas o lucro, mas tamb\u00e9m o [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":3404,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,10],"tags":[119,20,47],"class_list":["post-3403","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-recente","tag-brasilcap","tag-economia-verde","tag-financas"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3403","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=3403"}],"version-history":[{"count":1,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3403\/revisions"}],"predecessor-version":[{"id":3405,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/3403\/revisions\/3405"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/3404"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=3403"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=3403"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=3403"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}