{"id":2982,"date":"2020-09-18T12:12:46","date_gmt":"2020-09-18T12:12:46","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=2982"},"modified":"2020-09-18T12:12:46","modified_gmt":"2020-09-18T12:12:46","slug":"seja-mais-produtivo","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2020\/09\/18\/seja-mais-produtivo\/","title":{"rendered":"Seja mais produtivo!"},"content":{"rendered":"<p>\u00c9 muito comum terminarmos o dia e nos questionarmos se poder\u00edamos ter rendido mais e aproveitado melhor o nosso tempo. E isso vem acontecendo bastante, j\u00e1 que a rotina de muita gente acabou ficando mais \u201cbagun\u00e7ada\u201d nos \u00faltimos meses.<\/p>\n<p>O fato \u00e9 que o grande segredo para <strong>melhorarmos a nossa produtividade<\/strong> e garantir que estamos dando o m\u00e1ximo durante cada dia est\u00e1 em ter uma <strong>boa gest\u00e3o de tempo<\/strong>. Ou seja, saber aproveitar ao m\u00e1ximo cada hora de trabalho.<\/p>\n<p>Portanto, chegou o momento de deixar seus dias de procrastina\u00e7\u00e3o para tr\u00e1s e finalmente se tornar uma pessoa muito mais <strong>produtiva<\/strong> com essas dicas que separamos para ajud\u00e1-lo!<\/p>\n<p>Veja a seguir! \ud83d\ude42<\/p>\n<p>&#8211;<\/p>\n<h2><strong>Pense no dia seguinte<\/strong><\/h2>\n<p>Uma t\u00e9cnica que vai ajudar bastante na sua <strong>produtividade no dia a dia<\/strong> \u00e9 a de sempre se planejar com um dia de anteced\u00eancia. Ou seja, antes de dormir, separe alguns minutos para j\u00e1 montar uma lista de tudo o que voc\u00ea quer realizar no dia seguinte.<\/p>\n<p>Dessa forma, voc\u00ea j\u00e1 come\u00e7a suas atividades sabendo o que precisa ser cumprido at\u00e9 o final de cada dia, o que facilita <strong>organizar o seu tempo<\/strong> para fazer cada tarefa. Aos poucos, isso vai se tornar um h\u00e1bito para voc\u00ea e vai ajudar bastante na hora de colocar a m\u00e3o na massa.<\/p>\n<h2><strong>Conhe\u00e7a sua rotina<\/strong><\/h2>\n<p>Se tem algu\u00e9m que conhece bem a sua rotina, esse algu\u00e9m \u00e9 voc\u00ea mesmo. Ent\u00e3o, sabendo disso, responda a seguinte pergunta: em qual per\u00edodo do dia voc\u00ea funciona melhor? Para alguns, logo pela manh\u00e3 \u00e9 a resposta certa, outros preferem a noite.<\/p>\n<p>Se voc\u00ea souber em qual hor\u00e1rio voc\u00ea costuma render mais, \u00e9 poss\u00edvel distribuir as suas tarefas para que as mais complexas se encaixem nesse per\u00edodo e voc\u00ea possa tir\u00e1-las da frente no momento em que o seu rendimento \u00e9 melhor.<\/p>\n<h2><strong>Tenha foco no que quer resolver<\/strong><\/h2>\n<p>Uma coisa que atrapalha bastante na hora de tentar <strong>ser mais produtivo<\/strong> \u00e9 acumular diversas tarefas para resolver ao mesmo tempo. Isso tira completamente o seu foco, j\u00e1 que voc\u00ea vai ter que parar v\u00e1rias vezes para dar um pouco de aten\u00e7\u00e3o a cada assunto.<\/p>\n<p>Por isso, a melhor solu\u00e7\u00e3o \u00e9 sempre se manter 100% focado em um objetivo, conclu\u00ed-lo e s\u00f3 depois passar para a pr\u00f3xima tarefa. Voc\u00ea vai perceber que o seu rendimento ser\u00e1 muito melhor quando voc\u00ea se acostumar a trabalhar dessa forma.<\/p>\n<h2><strong>Priorize as dificuldades<\/strong><\/h2>\n<p>Durante a rotina, acabamos nos deparando com problemas que s\u00e3o simples de resolver e outros que envolvem um desafio bem maior. Por isso, a melhor solu\u00e7\u00e3o \u00e9 a de tentar encarar logo no come\u00e7o as suas tarefas mais dif\u00edceis.<\/p>\n<p>Dessa forma, voc\u00ea estar\u00e1 com a energia em alta e pronto para resolver seus desafios, deixando, assim, as coisas mais f\u00e1ceis para depois. Afinal, j\u00e1 que elas s\u00e3o simples, voc\u00ea pode resolv\u00ea-las rapidinho e sem tanto esfor\u00e7o.<\/p>\n<h2><strong>Organize-se<\/strong><\/h2>\n<p>Duas a\u00e7\u00f5es que v\u00e3o diretamente contra a sua <strong>produtividade<\/strong> s\u00e3o a desorganiza\u00e7\u00e3o e a falta de objetivos. Se voc\u00ea quer gerir melhor o seu tempo, saiba que uma \u00f3tima forma de come\u00e7ar \u00e9 sendo uma pessoa mais organizada.<\/p>\n<p>Portanto, ajuste seu ambiente de trabalho, crie uma listinha com tarefas do dia que fique sempre perto de voc\u00ea e, definitivamente, em pouco tempo, voc\u00ea estar\u00e1 sentindo que as suas horas est\u00e3o rendendo muito mais do que antigamente. Fa\u00e7a esse teste.<\/p>\n<p>&#8211;<\/p>\n<p>Agora vem a parte mais complicada que \u00e9 come\u00e7ar a aplicar todos esses pontos na sua rotina para colher os resultados. Mas pode ter certeza de que, em algumas semanas, voc\u00ea j\u00e1 sentir\u00e1 uma grande diferen\u00e7a no dia a dia.<\/p>\n<p>E aproveitando que voc\u00ea vai ter mais horas no seu dia, j\u00e1 que sua <strong>gest\u00e3o de tempo<\/strong> estar\u00e1 muito melhor, d\u00ea uma olhada tamb\u00e9m em <a href=\"http:\/\/blog.brasilcap.com.br\/post\/de-um-gas-na-sua-saude\">algumas dicas para ajudar a <strong>cuidar da sua sa\u00fade<\/strong><\/a> e tamb\u00e9m a <a href=\"http:\/\/blog.brasilcap.com.br\/post\/como-se-manter-calmo-nestes-dias-dificeis\">manter a calma nesses dias agitados que estamos vivendo<\/a>.<\/p>\n<p>Voc\u00ea tem alguma estrat\u00e9gia que usa na sua rotina para se tornar algu\u00e9m <strong>mais produtivo<\/strong> que esquecemos de falar? Ent\u00e3o deixe aqui um coment\u00e1rio e compartilhe esse conhecimento com os outros leitores!<\/p>\n<p><a href=\"http:\/\/blog.brasilcap.com.br\/post\/estamos-todos-juntos\"><strong>#EstamosTodosJuntos<\/strong><\/a><\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00c9 muito comum terminarmos o dia e nos questionarmos se poder\u00edamos ter rendido mais e aproveitado melhor o nosso tempo. E isso vem acontecendo bastante, j\u00e1 que a rotina de muita gente acabou ficando mais \u201cbagun\u00e7ada\u201d nos \u00faltimos meses. O fato \u00e9 que o grande segredo para melhorarmos a nossa produtividade e garantir que estamos [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2977,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9,10],"tags":[73,119,24,45,23,548,187,583,584,72],"class_list":["post-2982","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidades","category-destaque","category-recente","tag-bem-estar","tag-brasilcap","tag-cotidiano","tag-defina-prioridades","tag-dia-a-dia","tag-estamos-todos-juntos","tag-habitos-saudaveis","tag-produtividade","tag-tecnicas-de-produtividade","tag-vida"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2982","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2982"}],"version-history":[{"count":1,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2982\/revisions"}],"predecessor-version":[{"id":2983,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2982\/revisions\/2983"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/2977"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2982"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2982"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2982"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}