{"id":2845,"date":"2020-06-19T12:12:17","date_gmt":"2020-06-19T12:12:17","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=2845"},"modified":"2020-06-19T12:12:17","modified_gmt":"2020-06-19T12:12:17","slug":"faca-exercicios-no-conforto-de-casa","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2020\/06\/19\/faca-exercicios-no-conforto-de-casa\/","title":{"rendered":"Fa\u00e7a exerc\u00edcios no conforto de casa."},"content":{"rendered":"<p>Durante este per\u00edodo em que passamos a ficar mais tempo dentro de nossas casas, muita gente acabou adquirindo novos h\u00e1bitos em suas rotinas. Aprender novas atividades, cozinhar, cuidar da casa, estudar e, claro, fazer exerc\u00edcios.<\/p>\n<p>Mas, mesmo tendo mais tempo, n\u00e3o \u00e9 t\u00e3o f\u00e1cil come\u00e7ar a se exercitar todos os dias, j\u00e1 que isso requer bastante foco, disciplina e for\u00e7a de vontade! Afinal, quem a\u00ed n\u00e3o tem mais pregui\u00e7a s\u00f3 pelo fato de estar em casa?<\/p>\n<p>Por isso, para ajudar as pessoas que decidirem encarar esse desafio, n\u00f3s separamos algumas dicas que v\u00e3o te ajudar na hora de come\u00e7ar a se exercitar!<\/p>\n<p>Ent\u00e3o, deixe a pregui\u00e7a de lado e vamos l\u00e1!<\/p>\n<p>&#8211;<\/p>\n<h2><strong>Escolha o lugar certo<\/strong><\/h2>\n<p>Uma boa forma de come\u00e7ar a sua <strong>rotina de treinos<\/strong> \u00e9 escolhendo o lugar ideal para <strong>se exercitar dentro de casa<\/strong>. Pode ser no quintal, na varanda, na garagem ou at\u00e9 mesmo em algum cantinho da sala com um pouco mais de espa\u00e7o.<\/p>\n<p>O importante \u00e9 que seja um local onde voc\u00ea se sinta confort\u00e1vel e tenha liberdade para se mexer. Al\u00e9m disso, tente optar por um lugar que seja diferente de onde voc\u00ea se senta para trabalhar ou estudar. Assim fica mais f\u00e1cil entrar no clima dos exerc\u00edcios.<\/p>\n<h2><strong>Descubra o hor\u00e1rio ideal<\/strong><\/h2>\n<p>Todo mundo tem a hora certa para se exercitar. Alguns s\u00e3o muito mais ativos logo ao acordar, enquanto outros preferem deixar as <strong>atividades f\u00edsicas<\/strong> para o fim do dia. E \u00e9 importante que voc\u00ea descubra a hora certa para voc\u00ea.<\/p>\n<p>Ter um hor\u00e1rio definido vai te ajudar a criar o h\u00e1bito de se manter em movimento, <strong>fazendo exerc\u00edcios diariamente<\/strong> e se motivando a continuar.<\/p>\n<h2><strong>Mantenha uma rotina<\/strong><\/h2>\n<p>E falando em criar o h\u00e1bito, esta \u00e9 uma das partes mais importantes e dif\u00edceis de fazer <strong>exerc\u00edcios f\u00edsicos<\/strong>. Ainda mais quando estamos em casa, o que cria v\u00e1rias tenta\u00e7\u00f5es para deixarmos os treinos de lado.<\/p>\n<p>\u00c9 importante que voc\u00ea se esforce, especialmente nos primeiros dias, para se manter com uma rotina fixa de treinos na semana. Acredite: quanto mais tempo fizer, mais f\u00e1cil fica continuar! At\u00e9 porque voc\u00ea vai come\u00e7ar a ver e colher resultados. \ud83d\ude42<\/p>\n<h2><strong>Fa\u00e7a do seu jeito<\/strong><\/h2>\n<p>A melhor parte de <strong>fazer exerc\u00edcios na sua casa<\/strong> \u00e9 ter a chance de agir da forma como voc\u00ea se sente mais confort\u00e1vel. Coloque aquela m\u00fasica que te deixa animado, uma roupa confort\u00e1vel e sinta-se em casa (literalmente).<\/p>\n<p>Voc\u00ea n\u00e3o precisa se preocupar com a competitividade natural do ambiente de uma academia ou quanto peso voc\u00ea est\u00e1 levantando, afinal, \u00e9 voc\u00ea com voc\u00ea mesmo! Ent\u00e3o, aproveite essa vantagem!<\/p>\n<h2><strong>Converse com um profissional<\/strong><\/h2>\n<p><strong>Praticar exerc\u00edcios<\/strong> \u00e9 algo s\u00e9rio e, por isso, \u00e9 importante que voc\u00ea tenha, pelo menos, uma conversa com um profissional antes de sair fazendo treinos sem acompanhamento.<\/p>\n<p>Ainda bem que, com a internet, \u00e9 muito simples fazer uma consulta m\u00e9dica e encontrar um personal trainer que possa ajud\u00e1-lo a come\u00e7ar seus exerc\u00edcios e indicar a rotina mais certeira para voc\u00ea. Em alguns casos, eles podem at\u00e9 te acompanhar, ao vivo, por v\u00eddeo. Fa\u00e7a esse teste!<\/p>\n<p>&#8211;<\/p>\n<p>E a\u00ed? Que tal <strong>cuidar da sua sa\u00fade<\/strong> e come\u00e7ar a <strong>praticar alguns treinos<\/strong> na sua casa? Pode ter certeza de que, em pouco tempo, voc\u00ea se sentir\u00e1 muito mais disposto para encarar os desafios do dia a dia.<\/p>\n<p>E j\u00e1 que voc\u00ea decidiu cuidar do seu corpo, que tal tamb\u00e9m ver algumas dicas de <a href=\"http:\/\/blog.brasilcap.com.br\/post\/como-se-manter-calmo-nestes-dias-dificeis\">como tomar conta da sua <strong>sa\u00fade mental<\/strong><\/a>?<\/p>\n<p>Precisa de mais dicas? Ent\u00e3o, que tal dar aquela ligadinha para o seu amigo que tem o h\u00e1bito de treinar e pegar alguns conselhos com ele. Afinal, <a href=\"http:\/\/blog.brasilcap.com.br\/post\/estamos-todos-juntos\"><strong>estamos todos juntos<\/strong><\/a> passando por esse momento.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Durante este per\u00edodo em que passamos a ficar mais tempo dentro de nossas casas, muita gente acabou adquirindo novos h\u00e1bitos em suas rotinas. Aprender novas atividades, cozinhar, cuidar da casa, estudar e, claro, fazer exerc\u00edcios. Mas, mesmo tendo mais tempo, n\u00e3o \u00e9 t\u00e3o f\u00e1cil come\u00e7ar a se exercitar todos os dias, j\u00e1 que isso requer [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2838,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[4,9,10],"tags":[73,119,546,24,547,69,45,23,503,187,556,571],"class_list":["post-2845","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atualidades","category-destaque","category-recente","tag-bem-estar","tag-brasilcap","tag-coronavirus","tag-cotidiano","tag-covid-19","tag-cuidados","tag-defina-prioridades","tag-dia-a-dia","tag-exercicios","tag-habitos-saudaveis","tag-pandemia","tag-rotina-saudavel"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2845","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2845"}],"version-history":[{"count":1,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2845\/revisions"}],"predecessor-version":[{"id":2846,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2845\/revisions\/2846"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/2838"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2845"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2845"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2845"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}