{"id":2694,"date":"2020-04-08T18:49:38","date_gmt":"2020-04-08T18:49:38","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=2694"},"modified":"2020-04-08T20:16:38","modified_gmt":"2020-04-08T20:16:38","slug":"estamos-todos-juntos","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2020\/04\/08\/estamos-todos-juntos\/","title":{"rendered":"Estamos Todos Juntos"},"content":{"rendered":"<p>Como todos sabem, o mundo est\u00e1 passando por um momento complicado devido \u00e0 <strong>pandemia<\/strong> do <strong>coronav\u00edrus<\/strong>, o que acabou impactando na vida de cada um de n\u00f3s.<\/p>\n<p>Muitos est\u00e3o em casa, sem saber quando poder\u00e3o sair, muitos est\u00e3o tensos com seus trabalhos e, no fim das contas, todos n\u00f3s estamos cheios de incertezas de como as coisas v\u00e3o se desenrolar daqui pra frente.<\/p>\n<p>E isso faz com que o clima no ar fique pesado e as pessoas pessimistas. Afinal, nossa maior for\u00e7a sempre aparece quando damos as m\u00e3os, quando compartilhamos um abra\u00e7o ou quando simplesmente trocamos um sorriso!<\/p>\n<p>Por isso, a <strong>Brasilcap<\/strong> decidiu mudar esse cen\u00e1rio e trazer uma mensagem de otimismo. Assista!<\/p>\n<p><iframe loading=\"lazy\" title=\"Estamos Todos Juntos - Brasilcap\" width=\"500\" height=\"281\" src=\"https:\/\/www.youtube.com\/embed\/D-LvziYLmkQ?feature=oembed\" frameborder=\"0\" allow=\"accelerometer; autoplay; clipboard-write; encrypted-media; gyroscope; picture-in-picture; web-share\" referrerpolicy=\"strict-origin-when-cross-origin\" allowfullscreen><\/iframe><\/p>\n<p>Independente do que aconte\u00e7a, lembre-se que viveremos dias melhores. Em breve, nossa rotina voltar\u00e1 ao normal e poderemos nos encontrar.<\/p>\n<p>Ent\u00e3o, que tal levantarmos a cabe\u00e7a?<\/p>\n<p>Porque a gente pode at\u00e9 estar afastado fisicamente, mas, se prestar aten\u00e7\u00e3o, estamos mais unidos do que nunca!<\/p>\n<p><strong>Estamos Todos Juntos<\/strong><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Como todos sabem, o mundo est\u00e1 passando por um momento complicado devido \u00e0 pandemia do coronav\u00edrus, o que acabou impactando na vida de cada um de n\u00f3s. Muitos est\u00e3o em casa, sem saber quando poder\u00e3o sair, muitos est\u00e3o tensos com seus trabalhos e, no fim das contas, todos n\u00f3s estamos cheios de incertezas de como [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2695,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[3,9,10],"tags":[119,62,546,23,548,72],"class_list":["post-2694","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-capitalizacao","category-destaque","category-recente","tag-brasilcap","tag-capitalizacao","tag-coronavirus","tag-dia-a-dia","tag-estamos-todos-juntos","tag-vida"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2694","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2694"}],"version-history":[{"count":1,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2694\/revisions"}],"predecessor-version":[{"id":2696,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2694\/revisions\/2696"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/2695"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2694"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2694"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2694"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}