{"id":2365,"date":"2019-05-13T18:16:23","date_gmt":"2019-05-13T18:16:23","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=2365"},"modified":"2019-06-13T21:02:10","modified_gmt":"2019-06-13T21:02:10","slug":"6-coisas-que-voce-precisa-saber-sobre-a-chikungunya","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2019\/05\/13\/6-coisas-que-voce-precisa-saber-sobre-a-chikungunya\/","title":{"rendered":"6 coisas que voc\u00ea precisa saber sobre a chikungunya"},"content":{"rendered":"<p><span style=\"color: #000000;\">A Chikungunya voltou a ser not\u00edcia no Brasil. Cidad\u00e3os de todo o pa\u00eds v\u00eam sofrendo com esse insistente v\u00edrus, que pode causar dores intermin\u00e1veis e, at\u00e9 mesmo, levar o paciente \u00e0 morte (mesmo que isso seja bem raro). Para que voc\u00ea possa saber mais sobre sintomas, formas de cont\u00e1gio, maneiras de preven\u00e7\u00e3o e curiosidades da doen\u00e7a causada por ele, o Zero Perrengue preparou esse texto especial.<\/span><\/p>\n<h2><span style=\"font-size: large; color: #000000;\"><b>O que \u00e9 chikungunya?<\/b><\/span><\/h2>\n<p><span style=\"color: #000000;\">A chikungunya \u00e9 um v\u00edrus, transmitido pela f\u00eamea do mosquito Aedes Aegypti (em alguns poucos casos, tamb\u00e9m pelo Aedes albopictus). Seu nome, derivado do idioma swahili, significa \u201caqueles que se dobram\u201d, em refer\u00eancia \u00e0 apar\u00eancia curvada dos pacientes<\/span><br \/>\n<span style=\"color: #000000;\">atendidos durante a primeira epidemia documentada &#8211; que ocorreu na Tanz\u00e2nia.<\/span><\/p>\n<h2><span style=\"font-size: large; color: #000000;\"><b>Quais os sintomas?<\/b><\/span><\/h2>\n<p><span style=\"color: #000000;\">As semelhan\u00e7as entre dengue e febre chikungunya n\u00e3o se restringem ao mosquito transmissor. Muitos sintomas s\u00e3o bem parecidos, o que pode levar algumas pessoas a confundirem as duas doen\u00e7as. Eles incluem: febre alta, dores de cabe\u00e7a, mialgia (dor muscular), exantema (erup\u00e7\u00f5es na pele), conjuntivite e dores nas articula\u00e7\u00f5es. Essas dores articulares talvez sejam os sinais mais caracter\u00edsticos, uma vez que costumam perdurar por meses. Cerca de 30% dos infectados n\u00e3o desenvolvem sintomas.<\/span><\/p>\n<h2><span style=\"color: #000000;\"><span style=\"font-size: large;\"><b>O que fazer, caso voc\u00ea esteja <\/b><\/span><span style=\"font-size: large;\"><b>infectado<\/b><\/span><span style=\"font-size: large;\"><b>?<\/b><\/span><\/span><\/h2>\n<p><span style=\"color: #000000;\">Ainda n\u00e3o existe um tratamento espec\u00edfico para a chikungunya. O ideal \u00e9 que, primeiro, o paciente v\u00e1 a um m\u00e9dico para confirmar a doen\u00e7a, em at\u00e9 24 horas. Caso esteja infectado, deve ficar de repouso e se hidratar bastante. Para amenizar as dores e a febre, recomenda-se anti-inflamat\u00f3rios, analg\u00e9sicos e antit\u00e9rmicos. Por outro lado, deve-se evitar medicamentos com \u00e1cido acetilsalic\u00edlico (AAS), como a aspirina, devido ao risco de hemorragia.<\/span><\/p>\n<h2><span style=\"font-size: large; color: #000000;\"><b>Quanto tempo leva a cura?<\/b><\/span><\/h2>\n<p><span style=\"color: #000000;\">A febre chikungunya some, normalmente, 10 dias ap\u00f3s a manifesta\u00e7\u00e3o dos sintomas. Entretanto, as dores musculares podem persistir por muitos meses. Neste caso, \u00e9 preciso voltar \u00e0 unidade m\u00e9dica para novos exames.<\/span><\/p>\n<h2><span style=\"font-size: large; color: #000000;\"><b>\u00c9 poss\u00edvel a infec\u00e7\u00e3o de pessoa para pessoa?<\/b><\/span><\/h2>\n<p><span style=\"color: #000000;\">N\u00e3o! O \u00fanico modo de transmiss\u00e3o \u00e9 por meio dos mosquitos Aedes Aegypti ou Aedes albopictus.<\/span><\/p>\n<h2><span style=\"font-size: large; color: #000000;\"><b>Como se prevenir?<\/b><\/span><\/h2>\n<p><span style=\"color: #000000;\">Ainda n\u00e3o h\u00e1 vacina contra a chikungunya. Por isso, a melhor preven\u00e7\u00e3o \u00e9 combater a prolifera\u00e7\u00e3o do mosquito, evitando deixar \u00e1gua parada (o ambiente perfeito para as larvas do Aedes Aegypti se desenvolverem). Caso encontre algum foco, comunique as autoridades respons\u00e1veis.<\/span><\/p>\n<p><span style=\"color: #000000;\">Al\u00e9m disso, voc\u00ea pode utilizar telas em janelas e portas, para evitar a entrada dos mosquitos no ambiente, usar roupas compridas \u2013 cal\u00e7as e blusas \u2013 e, se vestir roupas que deixem \u00e1reas do corpo expostas, aplique repelente nessas \u00e1reas.<\/span><\/p>\n<p><span style=\"color: #000000;\">Quando n\u00e3o for poss\u00edvel, por algum motivo, eliminar focos do mosquito, como em terrenos baldios ou lixo acumulado na rua, a Secretaria Municipal de Sa\u00fade da sua cidade deve ser acionada para remover os poss\u00edveis criadouros.\u00a0<a style=\"color: #000000;\" href=\"http:\/\/www.10minutossalvamvidas.rj.gov.br\/Site\/Conteudo\/Denuncia.aspx\">Veja aqui como entrar em contato<\/a>.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>A Chikungunya voltou a ser not\u00edcia no Brasil. Cidad\u00e3os de todo o pa\u00eds v\u00eam sofrendo com esse insistente v\u00edrus, que pode causar dores intermin\u00e1veis e, at\u00e9 mesmo, levar o paciente \u00e0 morte (mesmo que isso seja bem raro). Para que voc\u00ea possa saber mais sobre sintomas, formas de cont\u00e1gio, maneiras de preven\u00e7\u00e3o e curiosidades da [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2366,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,5,10],"tags":[477,73,506,463,410,71],"class_list":["post-2365","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-meio_ambiente","category-recente","tag-aedes-aegypti","tag-bem-estar","tag-chikungunya","tag-prevencao","tag-responsabilidade-social","tag-saude"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2365","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2365"}],"version-history":[{"count":2,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2365\/revisions"}],"predecessor-version":[{"id":2377,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2365\/revisions\/2377"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/2366"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2365"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2365"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2365"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}