{"id":2130,"date":"2019-01-22T12:09:05","date_gmt":"2019-01-22T12:09:05","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=2130"},"modified":"2019-01-22T12:21:11","modified_gmt":"2019-01-22T12:21:11","slug":"prevencao-que-a-gente-sente-na-pele","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2019\/01\/22\/prevencao-que-a-gente-sente-na-pele\/","title":{"rendered":"Preven\u00e7\u00e3o que a gente sente na pele"},"content":{"rendered":"<p><span style=\"font-size: medium; color: #000000;\">Voc\u00ea \u00e9 daqueles que adoram aproveitar a esta\u00e7\u00e3o mais quente do ano para tomar um sol e pegar aquele bronze? A gente sabe que \u00e9 muito bom, mas cuidado! Essa \u00e9poca \u00e9 sempre prop\u00edcia para o surgimento de problemas causados pela insola\u00e7\u00e3o, como o c\u00e2ncer de pele. Confira as dicas do Zero Perrengue para curtir o calor do jeito certo e evitar essa terr\u00edvel doen\u00e7a.<\/span><\/p>\n<h2><span style=\"font-size: large; color: #000000;\"><b>O que \u00e9 o c\u00e2ncer de pele?<\/b><\/span><\/h2>\n<p><span style=\"font-size: medium; color: #000000;\">O c\u00e2ncer de pele \u00e9 uma prolifera\u00e7\u00e3o de c\u00e9lulas cut\u00e2neas anormais. \u00c9 o tipo de c\u00e2ncer mais comum e causa les\u00f5es na pele com aspecto de n\u00f3dulo, tumor ou mancha. Algumas vezes, h\u00e1 tamb\u00e9m sangramento. Se perceber qualquer um desses sintomas, procure um m\u00e9dico.<\/span><\/p>\n<h2><span style=\"font-size: large; color: #000000;\"><b>Quem tem mais chances de pegar?<\/b><\/span><\/h2>\n<p><span style=\"font-size: medium; color: #000000;\">Pessoas com cabelos, pele e olhos claros, aqueles com hist\u00f3rico de familiares que j\u00e1 sofreram com a doen\u00e7a, al\u00e9m dos que t\u00eam muitas pintas ou manchas na pele!<\/span><\/p>\n<h2><span style=\"font-size: large; color: #000000;\"><b>Como se prevenir?<\/b><\/span><\/h2>\n<p><span style=\"font-size: medium; color: #000000;\">Seguem algumas dicas para voc\u00ea evitar o c\u00e2ncer de pele:<\/span><\/p>\n<p><span style=\"font-size: medium; color: #000000;\">&#8211; Utilizar protetor solar sempre que for expor sua pele ao sol, com fator m\u00ednimo 15, reaplicando o produto a cada 2h;<\/span><\/p>\n<p><span style=\"font-size: medium; color: #000000;\">&#8211; Usar roupas e acess\u00f3rios que impedem a exposi\u00e7\u00e3o a raios UV; <\/span><\/p>\n<p><span style=\"font-size: medium; color: #000000;\">&#8211; Se for tomar um banho de sol ou for \u00e0 praia, evite escolher hor\u00e1rios entre 10h e 16h;<\/span><\/p>\n<p><span style=\"font-size: medium; color: #000000;\">&#8211; Evitar bronzeamento artificial;<\/span><\/p>\n<p><span style=\"font-size: medium; color: #000000;\">&#8211; Olhar sua pele uma vez ao m\u00eas, pelo menos.<\/span><\/p>\n<p><span style=\"font-size: medium; color: #000000;\">Aproveitem o sol com modera\u00e7\u00e3o! E bom ver\u00e3o.<\/span><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Voc\u00ea \u00e9 daqueles que adoram aproveitar a esta\u00e7\u00e3o mais quente do ano para tomar um sol e pegar aquele bronze? A gente sabe que \u00e9 muito bom, mas cuidado! Essa \u00e9poca \u00e9 sempre prop\u00edcia para o surgimento de problemas causados pela insola\u00e7\u00e3o, como o c\u00e2ncer de pele. Confira as dicas do Zero Perrengue para curtir [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2131,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,5,10],"tags":[187,102,71,358],"class_list":["post-2130","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-meio_ambiente","category-recente","tag-habitos-saudaveis","tag-saudavel","tag-saude","tag-verao"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2130","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2130"}],"version-history":[{"count":2,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2130\/revisions"}],"predecessor-version":[{"id":2136,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2130\/revisions\/2136"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/2131"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2130"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2130"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2130"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}