{"id":2126,"date":"2019-01-07T17:45:26","date_gmt":"2019-01-07T17:45:26","guid":{"rendered":"http:\/\/api.blog.brasilcap.com.br\/?p=2126"},"modified":"2019-01-07T17:45:26","modified_gmt":"2019-01-07T17:45:26","slug":"por-que-o-contato-com-a-natureza-faz-bem-no-verao","status":"publish","type":"post","link":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/2019\/01\/07\/por-que-o-contato-com-a-natureza-faz-bem-no-verao\/","title":{"rendered":"Por que o contato com a natureza faz bem no ver\u00e3o?"},"content":{"rendered":"<p><span style=\"color: #222222;\">A natureza \u00e9 um alicerce para o corpo e a mente. Ela <\/span>melhora a<b> mem\u00f3ria de curto prazo, recupera a energia mental, alivia o estresse, incentiva a criatividade e diminui as chances de morte precoce. <\/b><\/p>\n<p>Os dias mais bonitos no ver\u00e3o nos proporcionam este contato com a natureza. Por isso, veja alguns passeios que voc\u00ea possa fazer para renovar suas energias.<\/p>\n<h2><span style=\"font-size: large;\"><b>Caminhe no jardim<\/b><\/span><\/h2>\n<p>Olhar apenas o jardim da janela do seu quarto n\u00e3o leva a nada. Portanto, fa\u00e7a uma caminhada em volta do verde, certamente voc\u00ea vai come\u00e7ar a notar o local com outros olhos.<\/p>\n<h2><span style=\"font-size: large;\"><b>Fa\u00e7a trilhas<\/b><\/span><\/h2>\n<p>Se voc\u00ea \u00e9 adepto de exerc\u00edcios, procure fazer trilhas em grupos. A pr\u00e1tica \u00e9 encarada como uma forma de exerc\u00edcio f\u00edsico e tamb\u00e9m de relaxamento. Al\u00e9m disso, o indiv\u00edduo consegue se desligar das preocupa\u00e7\u00f5es di\u00e1rias e direciona \u00e0 concentra\u00e7\u00e3o.<\/p>\n<p>Al\u00e9m disso, a companhia de outras pessoas gera a comunicabilidade e a socializa\u00e7\u00e3o. A recompensa fica em tirar aquela foto t\u00e3o esperada no mirante do final da trilha.<\/p>\n<h2><span style=\"font-size: large;\"><b>V\u00e1 \u00e0 praia<\/b><\/span><\/h2>\n<p>Ir \u00e0 praia, pisar na areia, tomar banho de mar, sentir o vento, ver o p\u00f4r ou nascer do sol: um dia perfeito para a renova\u00e7\u00e3o mental. Essas atividades refrescam \u00e0 mente, e o pr\u00f3prio contato com a \u00e1gua salgada ajuda no combate de doen\u00e7as.<\/p>\n<h2><span style=\"font-size: large;\"><b>Relacione-se com o campo<\/b><\/span><\/h2>\n<p>A vida no campo remete \u00e0 liberdade e a um mundo sem preocupa\u00e7\u00f5es. \u00c9 evidente que a realidade n\u00e3o \u00e9 bem assim, mas s\u00f3 lidar com essa impress\u00e3o, a vida melhora e muito.<\/p>\n<p>Nesses lugares, andar a cavalo, comer um prato t\u00edpico da regi\u00e3o, tomar um banho de cachoeira ou simplesmente sentir o ar puro \u00e9 um convite para a felicidade.<\/p>\n<p>Pensando nisso, aproveite o ver\u00e3o e busque atividades com a natureza que possam proporcionar \u00e0 alegria e \u00e0 longevidade.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>A natureza \u00e9 um alicerce para o corpo e a mente. Ela melhora a mem\u00f3ria de curto prazo, recupera a energia mental, alivia o estresse, incentiva a criatividade e diminui as chances de morte precoce. Os dias mais bonitos no ver\u00e3o nos proporcionam este contato com a natureza. Por isso, veja alguns passeios que voc\u00ea [&hellip;]<\/p>\n","protected":false},"author":1,"featured_media":2127,"comment_status":"open","ping_status":"open","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[9,5,10],"tags":[21,428,309,19],"class_list":["post-2126","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-destaque","category-meio_ambiente","category-recente","tag-meio-ambiente","tag-natureza","tag-relacoes-humanas-e-meio-ambiente","tag-sustentabilidade"],"_links":{"self":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2126","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/comments?post=2126"}],"version-history":[{"count":1,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2126\/revisions"}],"predecessor-version":[{"id":2128,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/posts\/2126\/revisions\/2128"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media\/2127"}],"wp:attachment":[{"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/media?parent=2126"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/categories?post=2126"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/blog-homolog.brasilcap.com.br\/index.php\/wp-json\/wp\/v2\/tags?post=2126"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}